{"id":277,"date":"2022-09-23T12:10:50","date_gmt":"2022-09-23T12:10:50","guid":{"rendered":"https:\/\/www.leonatomachado.adv.br\/?page_id=277"},"modified":"2022-10-04T13:14:22","modified_gmt":"2022-10-04T13:14:22","slug":"especialidades","status":"publish","type":"page","link":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/","title":{"rendered":"ESPECIALIDADES"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"277\" class=\"elementor elementor-277\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-349079ff elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"349079ff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60b9b881\" data-id=\"60b9b881\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbacf71 elementor-widget elementor-widget-global elementor-global-439 elementor-widget-image\" data-id=\"dbacf71\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.leonatomachado.adv.br\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"570\" height=\"244\" src=\"https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/10\/Captura-de-Tela-2022-10-03-a\u0300s-17.51.04-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/10\/Captura-de-Tela-2022-10-03-a\u0300s-17.51.04-1.png 570w, https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/10\/Captura-de-Tela-2022-10-03-a\u0300s-17.51.04-1-300x128.png 300w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d08ca32\" data-id=\"3d08ca32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-60dee4ca elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60dee4ca\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-65e4b47a\" data-id=\"65e4b47a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-612efd1f elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"612efd1f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tAv. Paes de Barros, 444,\t\t\t\t\t<\/span>\n\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMooca, S\u00e3o Paulo - SP\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-124c3848\" data-id=\"124c3848\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37b32cef elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"37b32cef\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\t9:00 \u00e0s 18:00\t\t\t\t\t<\/span>\n\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSegunda - Feira a Sexta -  Feira\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3e1d3d6a\" data-id=\"3e1d3d6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a02ff9 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"39a02ff9\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h6 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tTelefones\t\t\t\t\t<\/span>\n\t\t\t\t<\/h6>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t(11) 3543-8415 \n\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1901296f\" data-id=\"1901296f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f40c3 elementor-widget elementor-widget-spacer\" data-id=\"74f40c3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06b192c elementor-button-info elementor-align-center elementor-widget elementor-widget-global elementor-global-336 elementor-widget-button\" data-id=\"06b192c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/wa.me\/5511999299128\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">WHATSAPP<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a2536 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-global elementor-global-355 elementor-widget-social-icons\" data-id=\"c1a2536\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-4b59969\" href=\"https:\/\/www.facebook.com\/leonatomachadoadv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-49dc429\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-ad9b25b\" href=\"https:\/\/www.instagram.com\/leonatomachadoadv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bb31d25 elementor-section-content-middle elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7bb31d25\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f213641\" data-id=\"f213641\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c0f41d elementor-nav-menu__align-center elementor-nav-menu--dropdown-mobile elementor-nav-menu--stretch elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"1c0f41d\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav migration_allowed=\"1\" migrated=\"0\" role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-1c0f41d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-218\"><a href=\"https:\/\/www.leonatomachado.adv.br\/\" class=\"elementor-item\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-344\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/o-que-fazemos\/\" class=\"elementor-item\">O QUE FAZEMOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-391\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/socios\/\" class=\"elementor-item\">S\u00d3CIOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-401\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/advogados-associados\/\" class=\"elementor-item\">EQUIPE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-280\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\" class=\"elementor-item\">ESPECIALIDADES<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-426\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/nossa-historia\/\" class=\"elementor-item\">NOSSA HIST\u00d3RIA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-486\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/artigos\/\" class=\"elementor-item\">ARTIGOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-226\"><a href=\"mailto:curriculum@leonato.com.br\" class=\"elementor-item\">TRABALHE CONOSCO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-225\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\">CONTATO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-1c0f41d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-218\"><a href=\"https:\/\/www.leonatomachado.adv.br\/\" class=\"elementor-item\" tabindex=\"-1\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-344\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/o-que-fazemos\/\" class=\"elementor-item\" tabindex=\"-1\">O QUE FAZEMOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-391\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/socios\/\" class=\"elementor-item\" tabindex=\"-1\">S\u00d3CIOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-401\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/advogados-associados\/\" class=\"elementor-item\" tabindex=\"-1\">EQUIPE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-280\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\" class=\"elementor-item\" tabindex=\"-1\">ESPECIALIDADES<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-426\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/nossa-historia\/\" class=\"elementor-item\" tabindex=\"-1\">NOSSA HIST\u00d3RIA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-486\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/artigos\/\" class=\"elementor-item\" tabindex=\"-1\">ARTIGOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-226\"><a href=\"mailto:curriculum@leonato.com.br\" class=\"elementor-item\" tabindex=\"-1\">TRABALHE CONOSCO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-225\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">CONTATO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63d7a77b elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"63d7a77b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=st2disxc7Wg&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-phone\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e3aae7f\" data-id=\"7e3aae7f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d67add elementor-widget elementor-widget-heading\" data-id=\"0d67add\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">leonatomachado.adv.br<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b384d0f premium-header-block premium-header-inline elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"b384d0f\" data-element_type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\t\t<h1 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">ESPECIALIDADES <\/span><\/h1> \t\t\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75d97045 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75d97045\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a4b29bd\" data-id=\"5a4b29bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c13b93c elementor-widget elementor-widget-spacer\" data-id=\"c13b93c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15b64f47 elementor-widget elementor-widget-heading\" data-id=\"15b64f47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">LEONATOMACHADO.ADV.BR<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd074e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd074e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93fe7f2\" data-id=\"93fe7f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b44a7fb elementor-widget elementor-widget-text-editor\" data-id=\"b44a7fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"p1\">\u2022 Direito Civil e Processual Civil<\/h3><p class=\"p3\">\u00c9 o ramo do Direito respons\u00e1vel por regular direitos e deveres de aspectos privados relativos \u00e0s pessoas, seus relacionamentos familiares, suas posses materiais, empresas, bens e outros elementos sociais a elas conectados.<\/p><p class=\"p5\">Direito Processual \u00e9 o respons\u00e1vel por estruturar os \u00f3rg\u00e3os de justi\u00e7a, disciplinando a forma dos processos judiciais na \u00e1rea c\u00edvel, isto \u00e9, de fazer valer o respeito \u00e0s leis de forma definitiva e coativa.<\/p><p class=\"p5\">O processo civil se divide em duas partes mais relevantes, a primeira sendo pelo conhecimento, que \u00e9 quando o processo \u00e9 instaurado com a finalidade de se conquistar a efetiva\u00e7\u00e3o de um direito; e a segunda \u00e9 pelo processo de execu\u00e7\u00e3o, que \u00e9 quando o direito j\u00e1 obteve seu reconhecimento, entretanto ainda se procura a consolida\u00e7\u00e3o f\u00edsica dele.<\/p><p class=\"p6\">Atua\u00e7\u00e3o:<\/p><p class=\"p6\">Propositura, defesa e acompanhamento de a\u00e7\u00f5es de Indeniza\u00e7\u00e3o por danos materiais e morais;<\/p><p class=\"p6\">C\u00f3digo de Prote\u00e7\u00e3o e Defesa do Consumidor;<\/p><p class=\"p6\">Assessoria, elabora\u00e7\u00e3o, revis\u00e3o e acompanhamento de a\u00e7\u00f5es de contratos civis, como Contratos de compra e venda; Venda em consigna\u00e7\u00e3o; Loca\u00e7\u00e3o; Incorpora\u00e7\u00e3o imobili\u00e1ria; Hipoteca; Penhor; Troca ou permuta; Assist\u00eancia m\u00e9dica e demais;<\/p><p class=\"p6\">Ajuizamento e defesa em a\u00e7\u00f5es de cobran\u00e7as;<\/p><p class=\"p7\">Propositura, defesa e acompanhamento de a\u00e7\u00f5es de presta\u00e7\u00e3o de contas, consigna\u00e7\u00e3o em pagamento, dep\u00f3sito e anula\u00e7\u00e3o;<\/p><p class=\"p6\">Recupera\u00e7\u00e3o de cr\u00e9ditos, atrav\u00e9s de medidas administrativas e judiciais, entre estas, propositura de a\u00e7\u00f5es de execu\u00e7\u00e3o, a\u00e7\u00f5es de cobran\u00e7a, a\u00e7\u00f5es monit\u00f3rias, a\u00e7\u00f5es de busca e apreens\u00e3o, habilita\u00e7\u00e3o de cr\u00e9ditos e impugna\u00e7\u00e3o de cr\u00e9ditos declarados;<\/p><p class=\"p6\">Assessoria para o recebimento de cr\u00e9ditos ou pagamento de d\u00e9bitos atrav\u00e9s de acordos judiciais ou extrajudiciais.<\/p><p class=\"p6\">Responsabilidade civil;<\/p><p class=\"p7\">Elabora\u00e7\u00e3o de notifica\u00e7\u00f5es e interpela\u00e7\u00f5es judiciais e extrajudiciais, com a inten\u00e7\u00e3o de atribuir responsabilidade e obter uma composi\u00e7\u00e3o amig\u00e1vel antes de instaurado o processo judicial.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa64f93 elementor-widget elementor-widget-text-editor\" data-id=\"fa64f93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"p1\">\u2022 Direito Condominial<\/h3><p class=\"p3\">Atualmente, as rela\u00e7\u00f5es entre cond\u00f4minos e a normatiza\u00e7\u00e3o s\u00e3o baseadas no C\u00f3digo Civil Brasileiro.<\/p><p class=\"p3\">Quanto a outras particularidades internas de condom\u00ednios \u2013 que variam de condom\u00ednio para condom\u00ednio \u2013 \u00e9 preciso citar a Conven\u00e7\u00e3o e o Regulamento Interno de cada propriedade. Estes documentos trazem, por exemplo, normas de conduta, entre outras determina\u00e7\u00f5es, n\u00e3o podendo, todavia, contrariar o disposto no C\u00f3digo Civil.<\/p><p class=\"p3\">Atua\u00e7\u00e3o:<\/p><p class=\"p3\">&#8211; Consultoria em Direito C\u00edvel, Trabalhista, Tribut\u00e1rio, Administrativo, Criminal ou outros ligados aos condom\u00ednios, al\u00e9m de representa\u00e7\u00e3o em \u00f3rg\u00e3os p\u00fablicos;<\/p><p class=\"p3\">&#8211; Consultoria Jur\u00eddica para Assembleia de condominio;<\/p><p class=\"p3\">&#8211;<span class=\"Apple-converted-space\">\u00a0 <\/span>Consultoria em aplica\u00e7\u00e3o de advert\u00eancia e multa;<\/p><p class=\"p3\">&#8211; Notifica\u00e7\u00f5es e Contranotifica\u00e7\u00f5es;<\/p><p class=\"p3\">&#8211; Direito de Vizinhan\u00e7a;<\/p><p class=\"p3\">&#8211; Revis\u00e3o e elabora\u00e7\u00e3o de conven\u00e7\u00e3o e regulamento interno;<\/p><p class=\"p3\">&#8211; Cobran\u00e7a de taxa condominial;<\/p><p class=\"p3\">&#8211;<span class=\"Apple-converted-space\">\u00a0 <\/span>Participa\u00e7\u00e3o em assembleia de implanta\u00e7\u00e3o;<\/p><p class=\"p3\">&#8211; Consultoria plena nas rela\u00e7\u00f5es trabalhistas, inclusive comparecimento em audi\u00eancias e elabora\u00e7\u00e3o de defesas e recursos;<\/p><p class=\"p3\">&#8211; Atua\u00e7\u00e3o direta na cobran\u00e7a de unidades inadimplentes na esfera extrajudicial atrav\u00e9s de departamento especializado, inclusive com plant\u00f5es para recupera\u00e7\u00e3o de cr\u00e9dito e permanente e rigorosa cobran\u00e7a judicial;<\/p><p class=\"p3\">&#8211; Elabora\u00e7\u00e3o de pareceres jur\u00eddicos para consolida\u00e7\u00e3o de assuntos pol\u00eamicos, tais como: vagas de garagem, responsabilidade do s\u00edndico, presta\u00e7\u00e3o de contas, direito de voto, vizinhan\u00e7a, animais no condom\u00ednio, dentre outros assuntos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d98e4a7\" data-id=\"d98e4a7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5269cd6 elementor-widget elementor-widget-text-editor\" data-id=\"5269cd6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"p1\">\u2022 Contencioso Civil<\/h3><p class=\"p2\">Resolu\u00e7\u00e3o de lit\u00edgios comuns a pessoas e empresas no cotidiano.<\/p><p class=\"p2\">Defesa em favor dos clientes em processos judiciais mais comuns, atuando perante as Varas Comuns e Juizados Especiais C\u00edveis de todo pa\u00eds.<\/p><h3 class=\"p1\">\u2022 Direito Imobili\u00e1rio<\/h3><p class=\"p2\">Direito Imobili\u00e1rio \u00e9 uma \u00e1rea abrangente e que atinge diversos assuntos relacionados \u00e0 im\u00f3veis, desde uma proposta de compra at\u00e9 a finaliza\u00e7\u00e3o do neg\u00f3cio, diversos passos s\u00e3o necess\u00e1rios para uma compra, venda ou loca\u00e7\u00e3o segura.<\/p><p class=\"p2\">Atuamos na presta\u00e7\u00e3o de servi\u00e7os de assessoria, na realiza\u00e7\u00e3o dos neg\u00f3cios imobili\u00e1rios incluindo a negocia\u00e7\u00e3o, completa an\u00e1lise de documentos, elabora\u00e7\u00e3o de contratos de compra e venda, de cess\u00e3o de direitos, loca\u00e7\u00e3o, comodato, doa\u00e7\u00e3o, da\u00e7\u00e3o em pagamento, entre outros.<\/p><p class=\"p2\">Atua\u00e7\u00e3o:<\/p><p class=\"p2\">&#8211; Usucapi\u00e3o Judicial e Extrajudicial;<\/p><p class=\"p2\">&#8211; Distrato de Compra e Venda;<\/p><p class=\"p2\">&#8211; Registro Imobili\u00e1rio de Terrenos, Im\u00f3veis Urbanos e Rural;<\/p><p class=\"p2\">&#8211; Leil\u00e3o de Im\u00f3veis \u2013 Arremate;<\/p><p class=\"p2\">&#8211; Extin\u00e7\u00e3o de Condom\u00ednio;<\/p><p class=\"p2\">&#8211; Contrato de Venda e Compra de im\u00f3vel;<\/p><p class=\"p2\">&#8211; Financiamento Imobili\u00e1rio;<\/p><p class=\"p2\">&#8211; Loca\u00e7\u00e3o Im\u00f3veis Residenciais, Comerciais e Shopping Centers;<\/p><p class=\"p2\">&#8211; Direito Imobili\u00e1rio para Condom\u00ednios;<\/p><p class=\"p2\">&#8211; Revis\u00e3o de Aluguel;<\/p><p class=\"p2\">&#8211; Consultoria de loca\u00e7\u00e3o de antenas de telefonia, Notifica\u00e7\u00e3o e A\u00e7\u00e3o Revisional de Aluguel.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7acbcf elementor-widget elementor-widget-text-editor\" data-id=\"d7acbcf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"p1\">\u2022 Direito do Trabalho<\/h3><p class=\"p3\">Nossa atua\u00e7\u00e3o vai al\u00e9m da pr\u00e1tica tradicional do Direito do Trabalho, fornecendo solu\u00e7\u00f5es inovadoras com abordagens inteligentes e integradas na assessoria a condom\u00ednios e empresas.<\/p><p class=\"p3\">Alinhado com as mais avan\u00e7adas pr\u00e1ticas do Direito Trabalhista, nossa equipe especializada est\u00e1 sempre atenta sobre as constantes modifica\u00e7\u00f5es na legisla\u00e7\u00e3o e jurisprud\u00eancias trabalhista. Auxiliamos condom\u00ednios e empresas atrav\u00e9s de assessoria consultiva sobre os mais diversos temas.<\/p><p class=\"p3\">Atua\u00e7\u00e3o:<\/p><p class=\"p3\">&#8211; Assessoria jur\u00eddica sobre Direitos trabalhistas;<\/p><p class=\"p3\">&#8211; Assessoria jur\u00eddica para demiss\u00f5es e acordos seguindo as diretrizes da nova CLT;<\/p><p class=\"p3\">&#8211; Pareceres tribut\u00e1rios envolvendo presta\u00e7\u00e3o de servi\u00e7os e colaboradores;<\/p><p class=\"p3\">&#8211; Defesas trabalhistas;<\/p><p class=\"p3\">&#8211; Termos de Ajuste de Conduta junto ao Minist\u00e9rio P\u00fablico do Trabalho.<\/p><h3 class=\"p1\">\u2022Direito Ambiental<\/h3><p class=\"p3\">Nossos profissionais est\u00e3o preparados para oferecer assessoria jur\u00eddica nas quest\u00f5es que envolvem a legisla\u00e7\u00e3o ambiental brasileira.<\/p><p class=\"p3\">Atua\u00e7\u00e3o:<\/p><p class=\"p3\">&#8211; Contencioso Ambiental administrativo e c\u00edvel;<\/p><p class=\"p3\">&#8211; Media\u00e7\u00e3o de Conflitos relacionados ao meio ambiente;<\/p><p class=\"p3\">&#8211; Assessoria em multas ambientais municipais e estaduais;<\/p><p class=\"p3\">&#8211; Assessoria em TCA \u2013 Termo de Compromisso Ambiental;<\/p><p class=\"p3\">&#8211; Assessoria em TAC \u2013 Termo de Ajuste de Conduta;<\/p><p class=\"p3\">&#8211; Licenciamento ambiental.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa2956d elementor-widget elementor-widget-spacer\" data-id=\"fa2956d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15029d7d elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"15029d7d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=LBmQJvWxfEE&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-phone\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-203c3de2\" data-id=\"203c3de2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ae3f65 elementor-widget elementor-widget-spacer\" data-id=\"0ae3f65\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d5f7026 elementor-widget elementor-widget-heading\" data-id=\"2d5f7026\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">leonatomachado.adv.br<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52d64a43 premium-header-inline elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"52d64a43\" data-element_type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\t\t<h1 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">Estamos prontos <\/span><span class=\"premium-dual-header-second-header \">para atender suas necessidades.<\/span><\/h1> \t\t\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55ff275a premium-header-block premium-header-inline elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"55ff275a\" data-element_type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\t\t<h1 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">ENTRE EM CONTATO <\/span><\/h1> \t\t\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ba2164 elementor-button-info elementor-align-center elementor-widget elementor-widget-global elementor-global-274 elementor-widget-button\" data-id=\"5ba2164\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/wa.me\/5511999299128\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">WHATSAPP<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c9e68 elementor-widget elementor-widget-spacer\" data-id=\"63c9e68\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4df94b1f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4df94b1f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5eb86971\" data-id=\"5eb86971\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33672d4 elementor-widget elementor-widget-heading\" data-id=\"33672d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Somos especialistas em Direito Civil e Processual Civil, Direito Imobili\u00e1rio, Direito de Fam\u00edlia e Direito Condominial.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-407ca52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"407ca52\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8de2a0e\" data-id=\"8de2a0e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72eb437 premium-header-inline premium-header-inline premium-header-inline elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"72eb437\" data-element_type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\t\t<h2 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">www.leonatomachado.adv.br <\/span><\/h2> \t\t\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a3448e elementor-nav-menu__align-left elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"8a3448e\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav migration_allowed=\"1\" migrated=\"0\" role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-8a3448e\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-218\"><a href=\"https:\/\/www.leonatomachado.adv.br\/\" class=\"elementor-item\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-344\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/o-que-fazemos\/\" class=\"elementor-item\">O QUE FAZEMOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-391\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/socios\/\" class=\"elementor-item\">S\u00d3CIOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-401\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/advogados-associados\/\" class=\"elementor-item\">EQUIPE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-280\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\" class=\"elementor-item\">ESPECIALIDADES<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-426\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/nossa-historia\/\" class=\"elementor-item\">NOSSA HIST\u00d3RIA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-486\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/artigos\/\" class=\"elementor-item\">ARTIGOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-226\"><a href=\"mailto:curriculum@leonato.com.br\" class=\"elementor-item\">TRABALHE CONOSCO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-225\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\">CONTATO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8a3448e\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-218\"><a href=\"https:\/\/www.leonatomachado.adv.br\/\" class=\"elementor-item\" tabindex=\"-1\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-344\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/o-que-fazemos\/\" class=\"elementor-item\" tabindex=\"-1\">O QUE FAZEMOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-391\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/socios\/\" class=\"elementor-item\" tabindex=\"-1\">S\u00d3CIOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-401\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/advogados-associados\/\" class=\"elementor-item\" tabindex=\"-1\">EQUIPE<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-280\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\" class=\"elementor-item\" tabindex=\"-1\">ESPECIALIDADES<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-426\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/nossa-historia\/\" class=\"elementor-item\" tabindex=\"-1\">NOSSA HIST\u00d3RIA<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-486\"><a href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/artigos\/\" class=\"elementor-item\" tabindex=\"-1\">ARTIGOS<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-226\"><a href=\"mailto:curriculum@leonato.com.br\" class=\"elementor-item\" tabindex=\"-1\">TRABALHE CONOSCO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-225\"><a href=\"#contato\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">CONTATO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f6c9bc1\" data-id=\"f6c9bc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1e38f5 elementor-widget elementor-widget-text-editor\" data-id=\"d1e38f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>LOCALIZA\u00c7\u00c3O<br \/>Av. Paes de Barros, 444, Mooca, S\u00e3o Paulo &#8211; SP<br \/>Telefone: (11) 3543-8415\/ (19) 2660-1880<br \/>Email: flavia.adv@leonato.com.br \/ Ilza.adv@leonato.com.br<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9223ba elementor-widget elementor-widget-global elementor-global-451 elementor-widget-menu-anchor\" data-id=\"a9223ba\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"contato\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638ad05 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-global elementor-global-352 elementor-widget-social-icons\" data-id=\"638ad05\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-a74bb07\" href=\"https:\/\/www.facebook.com\/leonatomachadoadv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-1166d45\" href=\"https:\/\/www.instagram.com\/leonatomachadoadv\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-6f2c628\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-589b9c76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"589b9c76\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2beca717\" data-id=\"2beca717\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5208dea4 elementor-widget elementor-widget-heading\" data-id=\"5208dea4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">www.up2group.com. 2022<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Av. Paes de Barros, 444, Mooca, S\u00e3o Paulo &#8211; SP 9:00 \u00e0s 18:00 Segunda &#8211; Feira a Sexta &#8211; Feira Telefones (11) 3543-8415 WHATSAPP Facebook Linkedin Instagram leonatomachado.adv.br ESPECIALIDADES LEONATOMACHADO.ADV.BR \u2022 Direito Civil e Processual Civil \u00c9 o ramo do Direito respons\u00e1vel por regular direitos e deveres de aspectos privados relativos \u00e0s pessoas, seus relacionamentos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-277","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ESPECIALIDADES - Leonato Machado Advogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESPECIALIDADES - Leonato Machado Advogados\" \/>\n<meta property=\"og:description\" content=\"Av. Paes de Barros, 444, Mooca, S\u00e3o Paulo &#8211; SP 9:00 \u00e0s 18:00 Segunda &#8211; Feira a Sexta &#8211; Feira Telefones (11) 3543-8415 WHATSAPP Facebook Linkedin Instagram leonatomachado.adv.br ESPECIALIDADES LEONATOMACHADO.ADV.BR \u2022 Direito Civil e Processual Civil \u00c9 o ramo do Direito respons\u00e1vel por regular direitos e deveres de aspectos privados relativos \u00e0s pessoas, seus relacionamentos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Leonato Machado Advogados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leonatomachadoadv\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T13:14:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\",\"url\":\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\",\"name\":\"ESPECIALIDADES - Leonato Machado Advogados\",\"isPartOf\":{\"@id\":\"https:\/\/www.leonatomachado.adv.br\/#website\"},\"datePublished\":\"2022-09-23T12:10:50+00:00\",\"dateModified\":\"2022-10-04T13:14:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.leonatomachado.adv.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESPECIALIDADES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leonatomachado.adv.br\/#website\",\"url\":\"https:\/\/www.leonatomachado.adv.br\/\",\"name\":\"Leonato Machado Advogados\",\"description\":\"Leonato Machado Advogados\",\"publisher\":{\"@id\":\"https:\/\/www.leonatomachado.adv.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leonatomachado.adv.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.leonatomachado.adv.br\/#organization\",\"name\":\"Leonato Machado Advogados\",\"url\":\"https:\/\/www.leonatomachado.adv.br\/\",\"sameAs\":[\"https:\/\/www.instagram.com\/leonatomachadoadv\/\",\"https:\/\/www.facebook.com\/leonatomachadoadv\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.leonatomachado.adv.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/08\/Leonato-Machado-Azul.png\",\"contentUrl\":\"https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/08\/Leonato-Machado-Azul.png\",\"width\":1080,\"height\":1080,\"caption\":\"Leonato Machado Advogados\"},\"image\":{\"@id\":\"https:\/\/www.leonatomachado.adv.br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESPECIALIDADES - Leonato Machado Advogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/","og_locale":"pt_BR","og_type":"article","og_title":"ESPECIALIDADES - Leonato Machado Advogados","og_description":"Av. Paes de Barros, 444, Mooca, S\u00e3o Paulo &#8211; SP 9:00 \u00e0s 18:00 Segunda &#8211; Feira a Sexta &#8211; Feira Telefones (11) 3543-8415 WHATSAPP Facebook Linkedin Instagram leonatomachado.adv.br ESPECIALIDADES LEONATOMACHADO.ADV.BR \u2022 Direito Civil e Processual Civil \u00c9 o ramo do Direito respons\u00e1vel por regular direitos e deveres de aspectos privados relativos \u00e0s pessoas, seus relacionamentos [&hellip;]","og_url":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/","og_site_name":"Leonato Machado Advogados","article_publisher":"https:\/\/www.facebook.com\/leonatomachadoadv","article_modified_time":"2022-10-04T13:14:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/","url":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/","name":"ESPECIALIDADES - Leonato Machado Advogados","isPartOf":{"@id":"https:\/\/www.leonatomachado.adv.br\/#website"},"datePublished":"2022-09-23T12:10:50+00:00","dateModified":"2022-10-04T13:14:22+00:00","breadcrumb":{"@id":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leonatomachado.adv.br\/index.php\/especialidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.leonatomachado.adv.br\/"},{"@type":"ListItem","position":2,"name":"ESPECIALIDADES"}]},{"@type":"WebSite","@id":"https:\/\/www.leonatomachado.adv.br\/#website","url":"https:\/\/www.leonatomachado.adv.br\/","name":"Leonato Machado Advogados","description":"Leonato Machado Advogados","publisher":{"@id":"https:\/\/www.leonatomachado.adv.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leonatomachado.adv.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.leonatomachado.adv.br\/#organization","name":"Leonato Machado Advogados","url":"https:\/\/www.leonatomachado.adv.br\/","sameAs":["https:\/\/www.instagram.com\/leonatomachadoadv\/","https:\/\/www.facebook.com\/leonatomachadoadv"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.leonatomachado.adv.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/08\/Leonato-Machado-Azul.png","contentUrl":"https:\/\/www.leonatomachado.adv.br\/wp-content\/uploads\/2022\/08\/Leonato-Machado-Azul.png","width":1080,"height":1080,"caption":"Leonato Machado Advogados"},"image":{"@id":"https:\/\/www.leonatomachado.adv.br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/pages\/277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/comments?post=277"}],"version-history":[{"count":55,"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/pages\/277\/revisions"}],"predecessor-version":[{"id":708,"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/pages\/277\/revisions\/708"}],"wp:attachment":[{"href":"https:\/\/www.leonatomachado.adv.br\/index.php\/wp-json\/wp\/v2\/media?parent=277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}